{"id":9242,"date":"2010-12-05T03:00:18","date_gmt":"2010-12-05T01:00:18","guid":{"rendered":"http:\/\/neulichimgarten.de\/blog\/?p=9242"},"modified":"2010-12-04T23:41:16","modified_gmt":"2010-12-04T21:41:16","slug":"das-fuenfte-tuerchen-des-neulichimgartendeblog-adventskalenders-2010","status":"publish","type":"post","link":"https:\/\/www.neulichimgarten.de\/blog\/das-fuenfte-tuerchen-des-neulichimgartendeblog-adventskalenders-2010\/","title":{"rendered":"Das fuenfte Tuerchen des neulichimgarten.de\/blog Adventskalenders 2010"},"content":{"rendered":"<p>Dass die Begeisterung fuer den Anbau von Gemuese nicht nur auf unser Land beschraenkt ist, sehen wir in meinem heutigen Video. Der nette junge Mann scheint sich bestens mit dem Anbau von Mais auszukennen. Ich nehme an, in etwas groesserem Massstab als ich <a href=\"http:\/\/neulichimgarten.de\/blog\/dies-und-das\/maisbeulenbrand-ustilago-maydis-zubereiten\/\" target=\"_self\">ihn so betreibe<\/a>. Jedenfalls, der Herr ist vollauf begeistert. Ganz nebenbei lernen wir auch noch, was man alles so mit Mais machen kann. Schade nur, auf die Problematik &#8222;Genmais&#8220; wird hier nicht eingegangen.<\/p>\n<p><object width=\"480\" height=\"385\" data=\"http:\/\/www.youtube.com\/v\/kSn6NJgAjCk?fs=1&amp;hl=de_DE\" type=\"application\/x-shockwave-flash\"><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/kSn6NJgAjCk?fs=1&amp;hl=de_DE\" \/><param name=\"allowfullscreen\" value=\"true\" \/><\/object><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dass die Begeisterung fuer den Anbau von Gemuese nicht nur auf unser Land beschraenkt ist, sehen wir in meinem heutigen Video. Der nette junge Mann scheint sich bestens mit dem Anbau von Mais auszukennen. Ich nehme an, in etwas groesserem Massstab als ich ihn so betreibe. Jedenfalls, der Herr ist vollauf begeistert. Ganz nebenbei lernen [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,42,51],"tags":[281,189],"_links":{"self":[{"href":"https:\/\/www.neulichimgarten.de\/blog\/wp-json\/wp\/v2\/posts\/9242"}],"collection":[{"href":"https:\/\/www.neulichimgarten.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.neulichimgarten.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.neulichimgarten.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.neulichimgarten.de\/blog\/wp-json\/wp\/v2\/comments?post=9242"}],"version-history":[{"count":0,"href":"https:\/\/www.neulichimgarten.de\/blog\/wp-json\/wp\/v2\/posts\/9242\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.neulichimgarten.de\/blog\/wp-json\/wp\/v2\/media?parent=9242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.neulichimgarten.de\/blog\/wp-json\/wp\/v2\/categories?post=9242"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.neulichimgarten.de\/blog\/wp-json\/wp\/v2\/tags?post=9242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}